{"id":18028,"date":"2022-09-18T00:00:00","date_gmt":"2022-09-18T00:00:00","guid":{"rendered":"https:\/\/fundaciolaninetadelsulls.org\/torneo-solidario\/"},"modified":"2025-07-07T12:28:56","modified_gmt":"2025-07-07T12:28:56","slug":"torneo-solidario","status":"publish","type":"post","link":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/","title":{"rendered":"TORNEO SOLIDARIO"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-5931 aligncenter\" src=\"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1-300x225.jpeg\" alt=\"\" width=\"356\" height=\"267\" \/><\/p>\n<p>El d\u00eda 17 de septiembre asistimos al primer torneo solidario de veteranas organizado por el CF. San Juan Desp\u00ed-San Pancracio del que nuestra fundaci\u00f3n fue la beneficiaria. Queremos agradecer la acogida y la implicaci\u00f3n de todo el equipo t\u00e9cnico y directivo del Club y muy especialmente a la jugadora Helena Balagu\u00e9 por ser la impulsora de la iniciativa.<\/p>\n<p>En el toneo participaron los equipos Mum&#8217;s WSS Barcelona, \u200b\u200bel Fc. Begues y el equipo anfitri\u00f3n. A destacar la deportividad vivida en el torneo donde los resultados pasaron a un segundo plano cuando al finalizar el torneo todo el mundo se quiso hacer una foto con la pancarta de la Fundaci\u00f3n.<\/p>\n<p>A destacar la presencia de toda la directiva del club, de las autoridades municipales y del periodista deportivo Ferran Latorre, quien est\u00e1 muy implicado en el proyecto deportivo del club.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 17 de septiembre asistimos al primer torneo solidario de veteranas organizado por el CF. San Juan Desp\u00ed-San Pancracio del que nuestra fundaci\u00f3n fue la beneficiaria. Queremos agradecer la acogida y la implicaci\u00f3n de todo el equipo t\u00e9cnico y directivo del Club y muy especialmente a la jugadora Helena Balagu\u00e9 por ser la impulsora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[],"class_list":["post-18028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TORNEO SOLIDARIO | Fundaci\u00f3 La Nineta dels Ulls<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TORNEO SOLIDARIO | Fundaci\u00f3 La Nineta dels Ulls\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda 17 de septiembre asistimos al primer torneo solidario de veteranas organizado por el CF. San Juan Desp\u00ed-San Pancracio del que nuestra fundaci\u00f3n fue la beneficiaria. Queremos agradecer la acogida y la implicaci\u00f3n de todo el equipo t\u00e9cnico y directivo del Club y muy especialmente a la jugadora Helena Balagu\u00e9 por ser la impulsora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 La Nineta dels Ulls\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-18T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T12:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TORNEO SOLIDARIO | Fundaci\u00f3 La Nineta dels Ulls","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/","og_locale":"es_ES","og_type":"article","og_title":"TORNEO SOLIDARIO | Fundaci\u00f3 La Nineta dels Ulls","og_description":"El d\u00eda 17 de septiembre asistimos al primer torneo solidario de veteranas organizado por el CF. San Juan Desp\u00ed-San Pancracio del que nuestra fundaci\u00f3n fue la beneficiaria. Queremos agradecer la acogida y la implicaci\u00f3n de todo el equipo t\u00e9cnico y directivo del Club y muy especialmente a la jugadora Helena Balagu\u00e9 por ser la impulsora [&hellip;]","og_url":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/","og_site_name":"Fundaci\u00f3 La Nineta dels Ulls","article_published_time":"2022-09-18T00:00:00+00:00","article_modified_time":"2025-07-07T12:28:56+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#article","isPartOf":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/"},"author":{"name":"admin","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#\/schema\/person\/3eccaf2a549ed72f66aa1d01ff3f5a1b"},"headline":"TORNEO SOLIDARIO","datePublished":"2022-09-18T00:00:00+00:00","dateModified":"2025-07-07T12:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/"},"wordCount":148,"commentCount":0,"publisher":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#organization"},"image":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#primaryimage"},"thumbnailUrl":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/","url":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/","name":"TORNEO SOLIDARIO | Fundaci\u00f3 La Nineta dels Ulls","isPartOf":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#primaryimage"},"image":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#primaryimage"},"thumbnailUrl":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1.jpeg","datePublished":"2022-09-18T00:00:00+00:00","dateModified":"2025-07-07T12:28:56+00:00","breadcrumb":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#primaryimage","url":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1.jpeg","contentUrl":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2022-09-17-at-22.30.34-1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/torneo-solidario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fundaciolaninetadelsulls.org\/es\/"},{"@type":"ListItem","position":2,"name":"TORNEO SOLIDARIO"}]},{"@type":"WebSite","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#website","url":"https:\/\/fundaciolaninetadelsulls.org\/es\/","name":"Fundaci\u00f3 La Nineta dels Ulls","description":"Objetivo Retinoblastoma","publisher":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundaciolaninetadelsulls.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#organization","name":"Fundaci\u00f3 La Nineta dels Ulls","url":"https:\/\/fundaciolaninetadelsulls.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2020\/12\/logo-fundacion-la-nineta-dels-ullst.png","contentUrl":"https:\/\/fundaciolaninetadelsulls.org\/wp-content\/uploads\/2020\/12\/logo-fundacion-la-nineta-dels-ullst.png","width":1467,"height":446,"caption":"Fundaci\u00f3 La Nineta dels Ulls"},"image":{"@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#\/schema\/person\/3eccaf2a549ed72f66aa1d01ff3f5a1b","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciolaninetadelsulls.org\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/265f6e939194518e3bea4bd7c1f3d8536537badc12519a87515855e398051aa4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265f6e939194518e3bea4bd7c1f3d8536537badc12519a87515855e398051aa4?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/fundaciolaninetadelsulls.org"]}]}},"_links":{"self":[{"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/posts\/18028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/comments?post=18028"}],"version-history":[{"count":0,"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/posts\/18028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/media\/16153"}],"wp:attachment":[{"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/media?parent=18028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/categories?post=18028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundaciolaninetadelsulls.org\/es\/wp-json\/wp\/v2\/tags?post=18028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}